{"id":6419,"date":"2026-05-06T06:11:01","date_gmt":"2026-05-06T06:11:01","guid":{"rendered":"https:\/\/ethica-group.com\/press-release\/ethica-group-ethica-ma-advisory-together-with-gff-in-the-acquisition-of-the-real-aromi-flavours-division-part-of-illva-saronno\/"},"modified":"2026-05-06T07:11:18","modified_gmt":"2026-05-06T07:11:18","slug":"ethica-group-ethica-ma-advisory-together-with-gff-in-the-acquisition-of-the-real-aromi-flavours-division-part-of-illva-saronno","status":"publish","type":"press_release","link":"https:\/\/ethica-group.com\/en\/news\/ethica-group-ethica-ma-advisory-together-with-gff-in-the-acquisition-of-the-real-aromi-flavours-division-part-of-illva-saronno\/","title":{"rendered":"Ethica Group \u2013 Ethica M&#038;A Advisory together with GFF in the acquisition of the Real Aromi Flavours Division (part of ILLVA Saronno)"},"content":{"rendered":"\n<p><p><em>Milano, 6 maggio 2026 <\/em>&#8211; Ethica Group, con il team di M&amp;A Advisory, ha assistito GFF S.r.l., produttore italiano leader di aromi ed essenze per il settore alimentare, nell\u2019acquisizione di Real Aromi Flavours Division, ramo di azienda di ILLVA Saronno S.p.A., attivo nella produzione di estratti naturali da spezie e vegetali.<\/p><\/p>\n\n<p>Fondata negli anni \u201950, Real Aromi Flavours Division ha registrato nel tempo una crescita sia organica sia attraverso l\u2019integrazione di linee esterne, sviluppando un portafoglio ampio e qualificato di estratti e prodotti naturali di elevata qualit\u00e0. Tali risultati sono resi possibili da impianti di estrazione e purificazione altamente automatizzati e da un laboratorio interno che, grazie a sofisticati sistemi di controllo, garantisce la costanza qualitativa dei prodotti nel tempo. La gamma, in continua evoluzione, trova applicazione in numerosi prodotti finiti, tra cui prodotti da forno, confetteria, latticini, wine &amp; spirits, sughi e salse, nonch\u00e9 nel settore nutraceutico.<\/p>\n\n<p>Questa operazione si innesta in un pi\u00f9 ampio percorso di sviluppo strategico di GFF ed \u00e8 orientata a rafforzarne e ampliarne il posizionamento attraverso l\u2019integrazione di un portafoglio clienti complementare e di soluzioni innovative ad alto valore aggiunto. Il ramo acquisito consentir\u00e0, in particolare, di accrescere la presenza della Societ\u00e0 presso clienti industriali e di consolidare il presidio di specifici segmenti di mercato, valorizzando relazioni commerciali consolidate e un\u2019offerta pienamente allineata al posizionamento di GFF. L\u2019integrazione delle attivit\u00e0 in GFF avverr\u00e0 nel segno della continuit\u00e0 delle relazioni commerciali e del livello di servizio, assicurando ai clienti e ai dipendenti un passaggio ordinato e privo di discontinuit\u00e0 operative.<\/p>\n\n<p>Enrico Giotti, CEO e fondatore di GFF ha dichiarato: \u201cQuesta acquisizione rappresenta un passo significativo nel percorso di crescita di GFF. L\u2019integrazione di un portafoglio clienti strategico e complementare ci consente di rafforzare la nostra presenza sul mercato e di ampliare ulteriormente la nostra capacit\u00e0 di rispondere in modo efficace e completo alle esigenze dei clienti. Garantiremo la piena continuit\u00e0 delle relazioni e del servizio, accompagnando i clienti in questa fase di integrazione con la massima attenzione e qualit\u00e0, caratteristiche che hanno da sempre contraddistinto il nostro DNA.\u201d<\/p>\n\n<p>Pietro Macchiarella, Head of M&amp;A and Business Development di Illva Saronno commenta: \u201cQuesta operazione rafforza la nostra strategia aziendale di semplificazione e di focalizzazione sugli asset core del Gruppo. Per preservare il nostro vantaggio competitivo, continueremo a mantenere internamente il know-how distintivo e gli impianti tecnologici, cos\u00ec da proseguire nello sviluppo degli estratti, concentrandoci esclusivamente sulla produzione a supporto dei business Beverage e Ingredients\u201d<\/p>\n\n<p>Nel contesto dell\u2019operazione, GFF \u00e8 stata assistita per gli aspetti finanziari da Ethica Group, con il team di M&amp;A Advisory composto da Paolo Russo, Stefano Buffoni e Sara stefanelli, mentre per gli aspetti legali dallo studio Calmonte.<\/p>\n","protected":false},"featured_media":0,"template":"","anno":[127],"class_list":["post-6419","press_release","type-press_release","status-publish","hentry","anno-2026-en-2"],"acf":[],"_links":{"self":[{"href":"https:\/\/ethica-group.com\/en\/wp-json\/wp\/v2\/press_release\/6419","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ethica-group.com\/en\/wp-json\/wp\/v2\/press_release"}],"about":[{"href":"https:\/\/ethica-group.com\/en\/wp-json\/wp\/v2\/types\/press_release"}],"wp:attachment":[{"href":"https:\/\/ethica-group.com\/en\/wp-json\/wp\/v2\/media?parent=6419"}],"wp:term":[{"taxonomy":"anno","embeddable":true,"href":"https:\/\/ethica-group.com\/en\/wp-json\/wp\/v2\/anno?post=6419"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}